{"id":1015,"count":1,"description":"","link":"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/","name":"date ideas completely free","slug":"date-ideas-completely-free","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v21.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>date ideas completely free Archives - Book of Us | Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"date ideas completely free Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/\" \/>\n<meta property=\"og:site_name\" content=\"Book of Us | Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/\",\"url\":\"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/\",\"name\":\"date ideas completely free Archives - Book of Us | Blog\",\"isPartOf\":{\"@id\":\"https:\/\/wordpress.bookofus.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wordpress.bookofus.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"date ideas completely free\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wordpress.bookofus.com\/blog\/#website\",\"url\":\"https:\/\/wordpress.bookofus.com\/blog\/\",\"name\":\"Book of Us | Blog\",\"description\":\"an imprint of I See Me!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wordpress.bookofus.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"date ideas completely free Archives - Book of Us | Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/","og_locale":"en_US","og_type":"article","og_title":"date ideas completely free Archives","og_url":"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/","og_site_name":"Book of Us | Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/","url":"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/","name":"date ideas completely free Archives - Book of Us | Blog","isPartOf":{"@id":"https:\/\/wordpress.bookofus.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/wordpress.bookofus.com\/blog\/tag\/date-ideas-completely-free\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wordpress.bookofus.com\/blog\/"},{"@type":"ListItem","position":2,"name":"date ideas completely free"}]},{"@type":"WebSite","@id":"https:\/\/wordpress.bookofus.com\/blog\/#website","url":"https:\/\/wordpress.bookofus.com\/blog\/","name":"Book of Us | Blog","description":"an imprint of I See Me!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wordpress.bookofus.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/wordpress.bookofus.com\/blog\/wp-json\/wp\/v2\/tags\/1015"}],"collection":[{"href":"https:\/\/wordpress.bookofus.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wordpress.bookofus.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wordpress.bookofus.com\/blog\/wp-json\/wp\/v2\/posts?tags=1015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}